{"id":1511,"date":"2022-01-12T05:41:17","date_gmt":"2022-01-12T05:41:17","guid":{"rendered":"https:\/\/fclatbz2dc.wpdns.site\/?post_type=product&#038;p=1511"},"modified":"2023-04-21T03:40:23","modified_gmt":"2023-04-21T03:40:23","slug":"hs-1530-1000w-open-type-laser-cutting-machine","status":"publish","type":"product","link":"https:\/\/mydery.com\/de\/produkt\/hs-1530-1000w-open-type-laser-cutting-machine\/","title":{"rendered":"HS-1530 1000W offene Laserschneidmaschine"},"content":{"rendered":"<p>HS-1530 1000W offene Laserschneidmaschine ist f\u00fcr alle verf\u00fcgbar <a href=\"https:\/\/mydery.com\/de\/produkt\/open-type-laser-stainless-steel-fiber-laser-cutting-machine\/\">Metall schneiden<\/a>, insbesondere zum Schneiden von Edelstahl, Eisen, Aluminium, Kupfer und anderen Metallmaterialien. Weit verbreitet in Blechen, Metallprodukten, Stahlkonstruktionen, Pr\u00e4zisionsmaschinen, Autoteilen, Brillen usw.<\/p>\n<p><img decoding=\"async\" class=\"wd-lazy-fade alignnone wp-image-12443\" src=\"https:\/\/mydery.com\/wp-content\/themes\/woodmart\/images\/lazy.svg\" data-src=\"http:\/\/mydery.com\/wp-content\/uploads\/2020\/12\/laser-cutting-machine-1.jpg\" alt=\"Laser-Schneide-Maschine\" width=\"800\" height=\"450\" title=\"\" srcset=\"\" data-srcset=\"https:\/\/mydery.com\/wp-content\/uploads\/2020\/12\/laser-cutting-machine-1.jpg 1300w, https:\/\/mydery.com\/wp-content\/uploads\/2020\/12\/laser-cutting-machine-1-300x169.jpg 300w, https:\/\/mydery.com\/wp-content\/uploads\/2020\/12\/laser-cutting-machine-1-1024x576.jpg 1024w, https:\/\/mydery.com\/wp-content\/uploads\/2020\/12\/laser-cutting-machine-1-768x432.jpg 768w, https:\/\/mydery.com\/wp-content\/uploads\/2020\/12\/laser-cutting-machine-1-1200x675.jpg 1200w, https:\/\/mydery.com\/wp-content\/uploads\/2020\/12\/laser-cutting-machine-1-600x337.jpg 600w, https:\/\/mydery.com\/wp-content\/uploads\/2020\/12\/laser-cutting-machine-1-150x84.jpg 150w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/p>\n<h3><img decoding=\"async\" class=\"wd-lazy-fade alignnone wp-image-12450\" src=\"https:\/\/mydery.com\/wp-content\/themes\/woodmart\/images\/lazy.svg\" data-src=\"http:\/\/mydery.com\/wp-content\/uploads\/2020\/07\/CNC-Fiber-Laser-Cutting-Machine-1.jpg\" alt=\"CNC-Faserlaser-Schneidemaschine (1)\" width=\"800\" height=\"1073\" title=\"\" srcset=\"\" data-srcset=\"https:\/\/mydery.com\/wp-content\/uploads\/2020\/07\/CNC-Fiber-Laser-Cutting-Machine-1.jpg 1300w, https:\/\/mydery.com\/wp-content\/uploads\/2020\/07\/CNC-Fiber-Laser-Cutting-Machine-1-224x300.jpg 224w, https:\/\/mydery.com\/wp-content\/uploads\/2020\/07\/CNC-Fiber-Laser-Cutting-Machine-1-764x1024.jpg 764w, https:\/\/mydery.com\/wp-content\/uploads\/2020\/07\/CNC-Fiber-Laser-Cutting-Machine-1-768x1030.jpg 768w, https:\/\/mydery.com\/wp-content\/uploads\/2020\/07\/CNC-Fiber-Laser-Cutting-Machine-1-1146x1536.jpg 1146w, https:\/\/mydery.com\/wp-content\/uploads\/2020\/07\/CNC-Fiber-Laser-Cutting-Machine-1-1200x1609.jpg 1200w, https:\/\/mydery.com\/wp-content\/uploads\/2020\/07\/CNC-Fiber-Laser-Cutting-Machine-1-600x804.jpg 600w, https:\/\/mydery.com\/wp-content\/uploads\/2020\/07\/CNC-Fiber-Laser-Cutting-Machine-1-150x201.jpg 150w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/> <img decoding=\"async\" class=\"wd-lazy-fade alignnone wp-image-12451\" src=\"https:\/\/mydery.com\/wp-content\/themes\/woodmart\/images\/lazy.svg\" data-src=\"http:\/\/mydery.com\/wp-content\/uploads\/2020\/07\/CNC-Fiber-Laser-Cutting-Machine-2.jpg\" alt=\"CNC-Faserlaser-Schneidemaschine (2)\" width=\"801\" height=\"916\" title=\"\" srcset=\"\" data-srcset=\"https:\/\/mydery.com\/wp-content\/uploads\/2020\/07\/CNC-Fiber-Laser-Cutting-Machine-2.jpg 1300w, https:\/\/mydery.com\/wp-content\/uploads\/2020\/07\/CNC-Fiber-Laser-Cutting-Machine-2-262x300.jpg 262w, https:\/\/mydery.com\/wp-content\/uploads\/2020\/07\/CNC-Fiber-Laser-Cutting-Machine-2-896x1024.jpg 896w, https:\/\/mydery.com\/wp-content\/uploads\/2020\/07\/CNC-Fiber-Laser-Cutting-Machine-2-768x878.jpg 768w, https:\/\/mydery.com\/wp-content\/uploads\/2020\/07\/CNC-Fiber-Laser-Cutting-Machine-2-1200x1372.jpg 1200w, https:\/\/mydery.com\/wp-content\/uploads\/2020\/07\/CNC-Fiber-Laser-Cutting-Machine-2-600x686.jpg 600w, https:\/\/mydery.com\/wp-content\/uploads\/2020\/07\/CNC-Fiber-Laser-Cutting-Machine-2-150x171.jpg 150w\" sizes=\"(max-width: 801px) 100vw, 801px\" \/><\/h3>\n<h3>Faserlaserquelle<\/h3>\n<p><img decoding=\"async\" class=\"wd-lazy-fade alignnone wp-image-12444\" src=\"https:\/\/mydery.com\/wp-content\/themes\/woodmart\/images\/lazy.svg\" data-src=\"http:\/\/mydery.com\/wp-content\/uploads\/2020\/12\/fiber-laser-source.jpg\" alt=\"Faserlaserquelle\" width=\"801\" height=\"358\" title=\"\" srcset=\"\" data-srcset=\"https:\/\/mydery.com\/wp-content\/uploads\/2020\/12\/fiber-laser-source.jpg 1300w, https:\/\/mydery.com\/wp-content\/uploads\/2020\/12\/fiber-laser-source-300x134.jpg 300w, https:\/\/mydery.com\/wp-content\/uploads\/2020\/12\/fiber-laser-source-1024x458.jpg 1024w, https:\/\/mydery.com\/wp-content\/uploads\/2020\/12\/fiber-laser-source-768x343.jpg 768w, https:\/\/mydery.com\/wp-content\/uploads\/2020\/12\/fiber-laser-source-18x8.jpg 18w, https:\/\/mydery.com\/wp-content\/uploads\/2020\/12\/fiber-laser-source-1200x536.jpg 1200w, https:\/\/mydery.com\/wp-content\/uploads\/2020\/12\/fiber-laser-source-600x268.jpg 600w, https:\/\/mydery.com\/wp-content\/uploads\/2020\/12\/fiber-laser-source-150x67.jpg 150w\" sizes=\"(max-width: 801px) 100vw, 801px\" \/><\/p>\n<h3>Laserkopf<\/h3>\n<p><img decoding=\"async\" class=\"wd-lazy-fade alignnone wp-image-12447\" src=\"https:\/\/mydery.com\/wp-content\/themes\/woodmart\/images\/lazy.svg\" data-src=\"http:\/\/mydery.com\/wp-content\/uploads\/2020\/12\/laser-head-1.jpg\" alt=\"Laserkopf\" width=\"802\" height=\"534\" title=\"\"><\/p>\n<h3>Haupteigenschaften<\/h3>\n<ul>\n<li>Der Abstand des Laserkopfes zum Werkst\u00fcck w\u00e4hrend des Schneidprozesses kann Kollisionsrisiken reduzieren. Es wird aufh\u00f6ren zu schneiden, wenn die kollidierende Platte.<\/li>\n<li>Es eignet sich zum Schneiden von Kohlenstoffstahl, Edelstahl, Aluminium, Messing und legierten Metallmaterialien.<\/li>\n<li>Eine automatische Schmiervorrichtung ist montiert, um sicherzustellen, dass<a href=\"https:\/\/youtu.be\/jAmrj9dkzd0\" target=\"_blank\" rel=\"noopener\"> glatte Maschine<\/a> ger\u00e4uscharmer Betrieb.<\/li>\n<li>Das System startet einen v\u00f6llig abnormalen Alarm und sendet ihn \u00fcber das Kontrollzentrum an die Schnittstelle, wenn das Ger\u00e4t abnormal ist.<\/li>\n<li>Hilfsgas-Niederdruck-Alarmfunktion Bietet Echtzeit-Druckerkennung und sendet abnormale Informationen, wenn der Druckwert niedriger ist als der optimale Schneideffekt und die optimale Pr\u00e4zision.<\/li>\n<li>Ein professionelles CNC-System und eine Schneidesoftware unterst\u00fctzen das CAD-Zeichnen und die Textprogrammierung.<\/li>\n<li>Hoher Kohlenstoffgehalt, hohe Druckfestigkeit und Arbeitstisch mit hoher H\u00e4rte.<\/li>\n<li>Geringe thermische Empfindlichkeit und Bettspaltempfindlichkeit reduzieren den Verlust der verwendeten Ausr\u00fcstung.<\/li>\n<li>Die Maschine besitzt eine komfortablere Bedienung, stabilere Leistung, langlebigere Qualit\u00e4t, h\u00f6here Schneideffizienz und einen breiteren Anwendungsbereich.<\/li>\n<\/ul>\n<h3>Maschinenkonstruktionen:<\/h3>\n<ul>\n<li><strong>K\u00f6rper der Faserlaserschneidmaschine:<\/strong> Der Maschinenk\u00f6rper besteht aus einem Maschinenschrank, einem Heckspiegel, einem Arbeitstisch und einem Z-Achsen-Ger\u00e4t, Betriebssteuerteilen und Gas, K\u00fchler.<\/li>\n<li><strong>Maschinenschrank:<\/strong> Durch die Anwendung der gesamten Bettschwei\u00dftechnik ist der Maschinenschrank stark tragbar und stabil. X \u3001 Y-Achse mit Servomotor und mit hochpr\u00e4zisen Untersetzungsgetrieben und qualitativ hochwertigen Getrieben. Es kann die \u00dcbertragungsgenauigkeit der Maschine effektiv garantieren. Au\u00dferdem ist es mit einem automatischen Schmiersystem und einem Staubsammelsystem ausgestattet und eignet sich besser zum Entsorgen von Abf\u00e4llen.<\/li>\n<li><strong>Querbalken:<\/strong> Die Verwendung von Stahlmaterial in Schiffsqualit\u00e4t, weniger Gewicht, aber mit einer besseren Anwendung kann garantieren, dass der Heckspiegel stark, tragbar und stabil ist.<\/li>\n<li><strong>Arbeitstisch:<\/strong> Der gesamte K\u00f6rper aus gegossenem Stahl ist auf jeder Seite mit einer Kugel ausgestattet, um eine bessere F\u00fctterung zu erm\u00f6glichen. Achtung: Optional mit Auf- und Ab-Zuf\u00fchrvorrichtung ausr\u00fcsten, um Materialsicherheit und Absturz zu sch\u00fctzen.<\/li>\n<li><strong>Z-Achse auf und ab:<\/strong> Wenn sich der Schneidkopf der Maschine an die Materialoberfl\u00e4che bewegt. Es \u00fcbertr\u00e4gt das Signal an das steuernde System. Damit es den besten Abstand zwischen dem Schneidkopf und der Materialoberfl\u00e4che effektiv steuern kann.<\/li>\n<li><strong>Gas- und K\u00fchlsystem:<\/strong> Es gibt zwei Arten von Gas, ein Teil ist das Angebot von Gas f\u00fcr <a href=\"https:\/\/www.harsle.com\/Laser-Cutting-Machine.html\" target=\"_blank\" rel=\"noopener\">maschinelles Schneiden<\/a>. wie Druckluft, Stickstoff und Sauerstoffgas, der andere soll das Komprimieren der Luft erleichtern, zum Beispiel die Absauggetriebedichtung und die Befestigungsklaue des Arbeitstisches.<\/li>\n<li><strong>Das Chiller-System besteht aus zwei Teilen:<\/strong> K\u00fchlwasser tritt in zwei Teile ein. Eine besteht darin, eine Schneidkopfposition zu betreten, um QBH zu sch\u00fctzen, und eine andere besteht darin, die Laserquelle zu sch\u00fctzen, um sie abzuk\u00fchlen und sie dann zum Wasserk\u00fchler zur\u00fcckzugeben.<\/li>\n<li><strong>Schneidkopf und folgendes System:<\/strong> Mit automatischem Brennweitenfolgesystem. Der Maschinenkopf kann automatisch den besten Abstand zwischen den Schneidk\u00f6pfen halten. Das Material f\u00fcr die beste Schnitttechnik.<\/li>\n<li><strong>CNC-Steuerungssystem: <\/strong>Das Steuersystem kann Windows XP Professional und Windows 7 zulassen. Damit kann es den Maschinenausschnitt mit den erforderlichen Parametern steuern.<\/li>\n<\/ul>","protected":false},"excerpt":{"rendered":"<p>Die offene Laserschneidmaschine HS-1530 1000W ist f\u00fcr das Schneiden aller Metalle erh\u00e4ltlich, insbesondere f\u00fcr Edelstahl, Eisen, Aluminium, Kupfer,<\/p>","protected":false},"featured_media":15017,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[18],"product_tag":[423,437,424],"class_list":["post-1511","product","type-product","status-publish","has-post-thumbnail","product_cat-open-type-laser-cutter","product_tag-1000w","product_tag-laser-cutting-machine","product_tag-open-type-laser-cutting-machine","first","instock","shipping-taxable","purchasable","product-type-simple"],"_links":{"self":[{"href":"https:\/\/mydery.com\/de\/wp-json\/wp\/v2\/product\/1511","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mydery.com\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/mydery.com\/de\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/mydery.com\/de\/wp-json\/wp\/v2\/comments?post=1511"}],"version-history":[{"count":0,"href":"https:\/\/mydery.com\/de\/wp-json\/wp\/v2\/product\/1511\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mydery.com\/de\/wp-json\/wp\/v2\/media\/15017"}],"wp:attachment":[{"href":"https:\/\/mydery.com\/de\/wp-json\/wp\/v2\/media?parent=1511"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/mydery.com\/de\/wp-json\/wp\/v2\/product_brand?post=1511"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/mydery.com\/de\/wp-json\/wp\/v2\/product_cat?post=1511"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/mydery.com\/de\/wp-json\/wp\/v2\/product_tag?post=1511"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}