{"id":1726,"date":"2021-02-18T08:37:42","date_gmt":"2021-02-18T08:37:42","guid":{"rendered":"https:\/\/fclatbz2dc.wpdns.site\/?p=1726"},"modified":"2024-01-25T07:12:48","modified_gmt":"2024-01-25T07:12:48","slug":"how-to-solve-laser-cutting-air-compressor","status":"publish","type":"post","link":"https:\/\/mydery.com\/es\/how-to-solve-laser-cutting-air-compressor\/","title":{"rendered":"\u00bfC\u00f3mo resolver que el compresor de aire de corte por l\u00e1ser contiene aceite?"},"content":{"rendered":"<p class=\"wp-block-paragraph\">En el proceso de corte por l\u00e1ser, el gas auxiliar es fundamental. Las principales funciones son:<br><strong>Combusti\u00f3n<\/strong>-mejorar la eficiencia de corte;<br><strong>Disipaci\u00f3n de calor<\/strong>-prevenir el endurecimiento del material;<br><strong>Purga<\/strong>-El gas presurizado expulsa la escoria de metal fundido, evita que el polvo obstruya la boquilla del l\u00e1ser y protege los componentes \u00f3pticos como la lente de enfoque.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-type-of-auxiliary-gas-for-laser-cutting\">Tipo de gas auxiliar para corte por l\u00e1ser<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">En la actualidad, tres tipos de gas auxiliar se utilizan ampliamente en la industria del corte por l\u00e1ser:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Ox\u00edgeno:<\/strong> Se utiliza principalmente para cortar materiales de acero al carbono. Dado que el ox\u00edgeno es una buena ayuda para la combusti\u00f3n, puede mejorar la eficiencia del corte. Sin embargo, dado que se formar\u00e1 una pel\u00edcula de \u00f3xido met\u00e1lico en la superficie de corte, tendr\u00e1 un cierto impacto en el mecanizado posterior.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Nitr\u00f3geno: <\/strong>Se utiliza principalmente para cortar acero inoxidable. El nitr\u00f3geno no reacciona con los metales. Por lo tanto, no formar\u00e1 una pel\u00edcula de \u00f3xido, lo que es bueno para el procesamiento posterior. Pero es precisamente esta ventaja la que conduce a una baja eficiencia de corte de nitr\u00f3geno y a un mayor consumo de gas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Aire comprimido: <\/strong>En comparaci\u00f3n con el ox\u00edgeno y el nitr\u00f3geno, el aire comprimido es m\u00e1s f\u00e1cil de obtener y m\u00e1s econ\u00f3mico. Dado que el aire contiene aproximadamente 20% de ox\u00edgeno y 78% de nitr\u00f3geno, esto determina que su eficiencia de corte es mucho menor que la del ox\u00edgeno, pero es mejor que el nitr\u00f3geno, y la superficie de trabajo despu\u00e9s del corte tambi\u00e9n es mejor que el ox\u00edgeno.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El costo por hora de usar aire comprimido es el m\u00e1s bajo. Esto no se ha calculado incluso cuando se utiliza ox\u00edgeno o nitr\u00f3geno como gas auxiliar, los otros procesos del equipo de corte por l\u00e1ser tambi\u00e9n necesitan aire comprimido. Por lo tanto, es m\u00e1s econ\u00f3mico utilizar aire comprimido como aire auxiliar cuando se permite la pieza de trabajo.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-air-compressor-for-laser-cutting-machine\">Compresor de aire para <a href=\"https:\/\/youtu.be\/5Ki5FMdstHE\" target=\"_blank\" rel=\"noopener\">m\u00e1quina de corte por l\u00e1ser<\/a><\/h2>\n\n\n\n<figure class=\"wp-block-image size-large is-resized\"><img class=\"wd-lazy-fade\" decoding=\"async\" width=\"749\" height=\"651\" src=\"https:\/\/mydery.com\/wp-content\/themes\/woodmart\/images\/lazy.svg\" data-src=\"http:\/\/mydery.com\/wp-content\/uploads\/2021\/02\/Air-compressor.jpg\" alt=\"Air compressor\" style=\"width:516px;height:auto\" title=\"\" srcset=\"\" data-srcset=\"https:\/\/mydery.com\/wp-content\/uploads\/2021\/02\/Air-compressor.jpg 749w, https:\/\/mydery.com\/wp-content\/uploads\/2021\/02\/Air-compressor-300x261.jpg 300w, https:\/\/mydery.com\/wp-content\/uploads\/2021\/02\/Air-compressor-14x12.jpg 14w, https:\/\/mydery.com\/wp-content\/uploads\/2021\/02\/Air-compressor-600x521.jpg 600w, https:\/\/mydery.com\/wp-content\/uploads\/2021\/02\/Air-compressor-150x130.jpg 150w\" sizes=\"(max-width: 749px) 100vw, 749px\" \/><figcaption><\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">La imagen de arriba es un equipo relativamente com\u00fan para m\u00e1quinas de corte por l\u00e1ser en el mercado. Este equipo es un dispositivo que integra remoci\u00f3n de agua, remoci\u00f3n de polvo y tanque de compensaci\u00f3n. Es f\u00e1cil de instalar y elimina la necesidad de que los clientes proporcionen tanques de almacenamiento de gas, secadores de fr\u00edo y filtros. El problema del dispositivo y el servicio postventa tambi\u00e9n es conveniente.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El proceso principal se muestra en la figura. Se agrega un filtro de eliminaci\u00f3n de aceite en la parte posterior del tanque de almacenamiento de aire. La mayor parte del agua l\u00edquida se puede eliminar a trav\u00e9s del filtro de condensaci\u00f3n y eliminaci\u00f3n de agua del tanque de almacenamiento de aire, y luego el aire comprimido se comprime a trav\u00e9s de un secador refrigerado. El punto de roc\u00edo se reduce a aproximadamente 5 \u2103 y, finalmente, el aceite l\u00edquido residual y el polvo se filtran a trav\u00e9s del filtro de m\u00faltiples etapas en la parte trasera. Finalmente ingrese al equipo de corte por l\u00e1ser.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"255\" src=\"https:\/\/mydery.com\/wp-content\/themes\/woodmart\/images\/lazy.svg\" data-src=\"http:\/\/mydery.com\/wp-content\/uploads\/2021\/02\/cutting-equipment-1024x255.png\" alt=\"equipo de corte\" class=\"wd-lazy-fade wp-image-1731\" title=\"\" srcset=\"\" data-srcset=\"https:\/\/mydery.com\/wp-content\/uploads\/2021\/02\/cutting-equipment-1024x255.png 1024w, https:\/\/mydery.com\/wp-content\/uploads\/2021\/02\/cutting-equipment-300x75.png 300w, https:\/\/mydery.com\/wp-content\/uploads\/2021\/02\/cutting-equipment-768x191.png 768w, https:\/\/mydery.com\/wp-content\/uploads\/2021\/02\/cutting-equipment-18x4.png 18w, https:\/\/mydery.com\/wp-content\/uploads\/2021\/02\/cutting-equipment-600x149.png 600w, https:\/\/mydery.com\/wp-content\/uploads\/2021\/02\/cutting-equipment-150x37.png 150w, https:\/\/mydery.com\/wp-content\/uploads\/2021\/02\/cutting-equipment.png 1080w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption><\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Esta configuraci\u00f3n trata bien el agua y el polvo en el aire comprimido y puede satisfacer las demandas de la m\u00e1quina de corte por l\u00e1ser. Sin embargo, ignora la influencia del aceite y solo se ocupa del tratamiento del aceite l\u00edquido. Si no se purifica el aceite gaseoso en el aire comprimido, el aire comprimido soplar\u00e1 la escoria fundida y el aire comprimido se condensar\u00e1 r\u00e1pidamente cuando se libere la presi\u00f3n. Cuando se libera la presi\u00f3n y se reduce la temperatura, se condensa en aceite l\u00edquido, contaminando as\u00ed el equipo de corte por l\u00e1ser.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El aire comprimido contiene agua nebulizada y aceite. Si no se limpia, la mezcla de aceite y agua que contiene contaminar\u00e1 el espejo protector, afectar\u00e1 ligeramente la eficiencia del corte con l\u00e1ser o dispersar\u00e1 la <a href=\"http:\/\/mydery.com\/es\/what-should-be-noticed-when-cutting-round-hole-with-laser-cutting-machine\/\">l\u00e1ser<\/a> enfoque, lo que resulta en productos impenetrables y productos de desecho. En casos graves, incluso puede provocar da\u00f1os en el cabezal l\u00e1ser de alta energ\u00eda y provocar mayores p\u00e9rdidas econ\u00f3micas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">air compressorair compressorair compressorair compressorair compressorair compressor<\/p>","protected":false},"excerpt":{"rendered":"<p>En el proceso de corte por l\u00e1ser, el gas auxiliar es fundamental. Las principales funciones son:<br \/>\nCombusti\u00f3n: mejora la eficiencia de corte;<br \/>\nLa disipaci\u00f3n de calor evita el endurecimiento del material;<br \/>\nPurga: el gas presurizado expulsa la escoria de metal fundido, evita que el polvo obstruya la boquilla del l\u00e1ser y protege los componentes \u00f3pticos, como la lente de enfoque.<\/p>","protected":false},"author":4,"featured_media":1727,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[551,786,787,785,701],"class_list":["post-1726","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-laser-cutting-machine","tag-auxiliary-gas","tag-compressed-air","tag-laser-head","tag-oxygen","tag-precision-laser-cutting"],"jetpack_featured_media_url":"https:\/\/mydery.com\/wp-content\/uploads\/2021\/02\/How-to-solve-laser-cutting-air-compressor-contains-oil.jpg","_links":{"self":[{"href":"https:\/\/mydery.com\/es\/wp-json\/wp\/v2\/posts\/1726","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mydery.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mydery.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mydery.com\/es\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/mydery.com\/es\/wp-json\/wp\/v2\/comments?post=1726"}],"version-history":[{"count":0,"href":"https:\/\/mydery.com\/es\/wp-json\/wp\/v2\/posts\/1726\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mydery.com\/es\/wp-json\/wp\/v2\/media\/1727"}],"wp:attachment":[{"href":"https:\/\/mydery.com\/es\/wp-json\/wp\/v2\/media?parent=1726"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mydery.com\/es\/wp-json\/wp\/v2\/categories?post=1726"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mydery.com\/es\/wp-json\/wp\/v2\/tags?post=1726"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}