{"id":1511,"date":"2022-01-12T05:41:17","date_gmt":"2022-01-12T05:41:17","guid":{"rendered":"https:\/\/fclatbz2dc.wpdns.site\/?post_type=product&#038;p=1511"},"modified":"2023-04-21T03:40:23","modified_gmt":"2023-04-21T03:40:23","slug":"hs-1530-1000w-open-type-laser-cutting-machine","status":"publish","type":"product","link":"https:\/\/mydery.com\/it\/prodotto\/hs-1530-1000w-open-type-laser-cutting-machine\/","title":{"rendered":"Macchina da taglio laser di tipo aperto HS-1530 1000W"},"content":{"rendered":"<p>La macchina da taglio laser di tipo aperto HS-1530 1000W \u00e8 disponibile per tutti <a href=\"https:\/\/mydery.com\/it\/prodotto\/open-type-laser-stainless-steel-fiber-laser-cutting-machine\/\">taglio di metalli<\/a>, in particolare per il taglio di acciaio inossidabile, ferro, alluminio, rame e altri materiali metallici. Ampiamente usato in lamiera, prodotti in metallo, struttura in acciaio, macchinari di precisione, ricambi auto, occhiali e cos\u00ec via.<\/p>\n<p><img decoding=\"async\" class=\"wd-lazy-fade alignnone wp-image-12443\" src=\"https:\/\/mydery.com\/wp-content\/themes\/woodmart\/images\/lazy.svg\" data-src=\"http:\/\/mydery.com\/wp-content\/uploads\/2020\/12\/laser-cutting-machine-1.jpg\" alt=\"macchina da taglio laser\" width=\"800\" height=\"450\" title=\"\" srcset=\"\" data-srcset=\"https:\/\/mydery.com\/wp-content\/uploads\/2020\/12\/laser-cutting-machine-1.jpg 1300w, https:\/\/mydery.com\/wp-content\/uploads\/2020\/12\/laser-cutting-machine-1-300x169.jpg 300w, https:\/\/mydery.com\/wp-content\/uploads\/2020\/12\/laser-cutting-machine-1-1024x576.jpg 1024w, https:\/\/mydery.com\/wp-content\/uploads\/2020\/12\/laser-cutting-machine-1-768x432.jpg 768w, https:\/\/mydery.com\/wp-content\/uploads\/2020\/12\/laser-cutting-machine-1-1200x675.jpg 1200w, https:\/\/mydery.com\/wp-content\/uploads\/2020\/12\/laser-cutting-machine-1-600x337.jpg 600w, https:\/\/mydery.com\/wp-content\/uploads\/2020\/12\/laser-cutting-machine-1-150x84.jpg 150w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/p>\n<h3><img decoding=\"async\" class=\"wd-lazy-fade alignnone wp-image-12450\" src=\"https:\/\/mydery.com\/wp-content\/themes\/woodmart\/images\/lazy.svg\" data-src=\"http:\/\/mydery.com\/wp-content\/uploads\/2020\/07\/CNC-Fiber-Laser-Cutting-Machine-1.jpg\" alt=\"Macchina da taglio laser a fibra CNC (1)\" width=\"800\" height=\"1073\" title=\"\" srcset=\"\" data-srcset=\"https:\/\/mydery.com\/wp-content\/uploads\/2020\/07\/CNC-Fiber-Laser-Cutting-Machine-1.jpg 1300w, https:\/\/mydery.com\/wp-content\/uploads\/2020\/07\/CNC-Fiber-Laser-Cutting-Machine-1-224x300.jpg 224w, https:\/\/mydery.com\/wp-content\/uploads\/2020\/07\/CNC-Fiber-Laser-Cutting-Machine-1-764x1024.jpg 764w, https:\/\/mydery.com\/wp-content\/uploads\/2020\/07\/CNC-Fiber-Laser-Cutting-Machine-1-768x1030.jpg 768w, https:\/\/mydery.com\/wp-content\/uploads\/2020\/07\/CNC-Fiber-Laser-Cutting-Machine-1-1146x1536.jpg 1146w, https:\/\/mydery.com\/wp-content\/uploads\/2020\/07\/CNC-Fiber-Laser-Cutting-Machine-1-1200x1609.jpg 1200w, https:\/\/mydery.com\/wp-content\/uploads\/2020\/07\/CNC-Fiber-Laser-Cutting-Machine-1-600x804.jpg 600w, https:\/\/mydery.com\/wp-content\/uploads\/2020\/07\/CNC-Fiber-Laser-Cutting-Machine-1-150x201.jpg 150w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/> <img decoding=\"async\" class=\"wd-lazy-fade alignnone wp-image-12451\" src=\"https:\/\/mydery.com\/wp-content\/themes\/woodmart\/images\/lazy.svg\" data-src=\"http:\/\/mydery.com\/wp-content\/uploads\/2020\/07\/CNC-Fiber-Laser-Cutting-Machine-2.jpg\" alt=\"Macchina da taglio laser a fibra CNC (2)\" width=\"801\" height=\"916\" title=\"\" srcset=\"\" data-srcset=\"https:\/\/mydery.com\/wp-content\/uploads\/2020\/07\/CNC-Fiber-Laser-Cutting-Machine-2.jpg 1300w, https:\/\/mydery.com\/wp-content\/uploads\/2020\/07\/CNC-Fiber-Laser-Cutting-Machine-2-262x300.jpg 262w, https:\/\/mydery.com\/wp-content\/uploads\/2020\/07\/CNC-Fiber-Laser-Cutting-Machine-2-896x1024.jpg 896w, https:\/\/mydery.com\/wp-content\/uploads\/2020\/07\/CNC-Fiber-Laser-Cutting-Machine-2-768x878.jpg 768w, https:\/\/mydery.com\/wp-content\/uploads\/2020\/07\/CNC-Fiber-Laser-Cutting-Machine-2-1200x1372.jpg 1200w, https:\/\/mydery.com\/wp-content\/uploads\/2020\/07\/CNC-Fiber-Laser-Cutting-Machine-2-600x686.jpg 600w, https:\/\/mydery.com\/wp-content\/uploads\/2020\/07\/CNC-Fiber-Laser-Cutting-Machine-2-150x171.jpg 150w\" sizes=\"(max-width: 801px) 100vw, 801px\" \/><\/h3>\n<h3>Sorgente laser in fibra<\/h3>\n<p><img decoding=\"async\" class=\"wd-lazy-fade alignnone wp-image-12444\" src=\"https:\/\/mydery.com\/wp-content\/themes\/woodmart\/images\/lazy.svg\" data-src=\"http:\/\/mydery.com\/wp-content\/uploads\/2020\/12\/fiber-laser-source.jpg\" alt=\"sorgente laser in fibra\" width=\"801\" height=\"358\" title=\"\" srcset=\"\" data-srcset=\"https:\/\/mydery.com\/wp-content\/uploads\/2020\/12\/fiber-laser-source.jpg 1300w, https:\/\/mydery.com\/wp-content\/uploads\/2020\/12\/fiber-laser-source-300x134.jpg 300w, https:\/\/mydery.com\/wp-content\/uploads\/2020\/12\/fiber-laser-source-1024x458.jpg 1024w, https:\/\/mydery.com\/wp-content\/uploads\/2020\/12\/fiber-laser-source-768x343.jpg 768w, https:\/\/mydery.com\/wp-content\/uploads\/2020\/12\/fiber-laser-source-18x8.jpg 18w, https:\/\/mydery.com\/wp-content\/uploads\/2020\/12\/fiber-laser-source-1200x536.jpg 1200w, https:\/\/mydery.com\/wp-content\/uploads\/2020\/12\/fiber-laser-source-600x268.jpg 600w, https:\/\/mydery.com\/wp-content\/uploads\/2020\/12\/fiber-laser-source-150x67.jpg 150w\" sizes=\"(max-width: 801px) 100vw, 801px\" \/><\/p>\n<h3>Testa laser<\/h3>\n<p><img decoding=\"async\" class=\"wd-lazy-fade alignnone wp-image-12447\" src=\"https:\/\/mydery.com\/wp-content\/themes\/woodmart\/images\/lazy.svg\" data-src=\"http:\/\/mydery.com\/wp-content\/uploads\/2020\/12\/laser-head-1.jpg\" alt=\"testa laser\" width=\"802\" height=\"534\" title=\"\"><\/p>\n<h3>Caratteristiche principali<\/h3>\n<ul>\n<li>La testa del laser che mantiene la distanza dal pezzo durante il processo di taglio pu\u00f2 ridurre i rischi di collisione. Smetter\u00e0 di tagliare quando la piastra si scontra.<\/li>\n<li>\u00c8 adatto per il taglio di acciaio al carbonio, acciaio inossidabile, alluminio, ottone e materiali in lega metallica.<\/li>\n<li>Un dispositivo di lubrificazione automatico \u00e8 montato per garantire un<a href=\"https:\/\/youtu.be\/jAmrj9dkzd0\" target=\"_blank\" rel=\"noopener\"> macchina liscia<\/a> funzionamento a bassa rumorosit\u00e0.<\/li>\n<li>Il sistema avvier\u00e0 un allarme completamente anomalo e lo trasmetter\u00e0 all&#039;interfaccia attraverso il centro di controllo quando l&#039;apparecchiatura \u00e8 anormale.<\/li>\n<li>Funzione di allarme di bassa pressione del gas ausiliario Fornisce il rilevamento della pressione in tempo reale, inviando informazioni anomale quando il valore della pressione \u00e8 inferiore all&#039;effetto di taglio e alla precisione ottimali.<\/li>\n<li>Un sistema CNC professionale e un software di taglio supportano il disegno CAD e la programmazione del testo.<\/li>\n<li>Alto contenuto di carbonio, elevata resistenza alla compressione e piano di lavoro ad alta durezza.<\/li>\n<li>La bassa sensibilit\u00e0 termica e la sensibilit\u00e0 al gap del letto riducono la perdita di apparecchiature in uso.<\/li>\n<li>La macchina possiede un funzionamento pi\u00f9 confortevole, prestazioni pi\u00f9 stabili, una qualit\u00e0 pi\u00f9 duratura, una maggiore efficienza di taglio e un campo di applicazione pi\u00f9 ampio.<\/li>\n<\/ul>\n<h3>Costruzioni di macchine:<\/h3>\n<ul>\n<li><strong>Corpo macchina taglio laser fibra:<\/strong> Il corpo macchina \u00e8 costituito da un armadio macchina, traversa, tavolo di lavoro e dispositivo dell&#039;asse Z, parti di controllo del funzionamento e gas, refrigeratore.<\/li>\n<li><strong>Armadio macchina:<\/strong> Adottando l&#039;intera tecnica di saldatura del letto, l&#039;armadio della macchina \u00e8 resistente e stabile. X \u3001 Asse Y che adotta il servomotore e con riduttori ad alta precisione e ingranaggi di buona qualit\u00e0. Pu\u00f2 garantire efficacemente la precisione di trasferimento della macchina. Inoltre, \u00e8 dotato di un sistema di lubrificazione automatico, sistema di raccolta della polvere ed \u00e8 migliore per uscire dai rifiuti.<\/li>\n<li><strong>Traversa:<\/strong> Adottando materiale in acciaio stile nave di qualit\u00e0, meno peso, ma con una migliore applicazione, pu\u00f2 garantire che lo specchio di poppa sia resistente, indossabile e stabile.<\/li>\n<li><strong>Tavolo di lavoro:<\/strong> Il corpo interamente in acciaio fuso \u00e8 inoltre dotato di una sfera su ogni lato per facilitare un migliore lavoro di alimentazione. Attenzione: Dotare opzionalmente di un dispositivo di alimentazione su e gi\u00f9 per proteggere la sicurezza del materiale e l&#039;incidente.<\/li>\n<li><strong>Asse Z su e gi\u00f9:<\/strong> Quando la testa di taglio della macchina si sposta sulla superficie del materiale. Trasferir\u00e0 il segnale al sistema di controllo. In modo che possa controllare efficacemente la migliore distanza tra la testa di taglio e la superficie del materiale.<\/li>\n<li><strong>Gas e sistema di refrigerazione:<\/strong> Ci sono due tipi di gas, una parte \u00e8 offrire gas per <a href=\"https:\/\/www.harsle.com\/Laser-Cutting-Machine.html\" target=\"_blank\" rel=\"noopener\">taglio a macchina<\/a>. come aria compressa, azoto e gas ossigeno, l&#039;altro \u00e8 quello di facilitare la compressione dell&#039;aria, ad esempio la guarnizione dell&#039;ingranaggio dell&#039;aspiratore e l&#039;artiglio di fissaggio del piano di lavoro.<\/li>\n<li><strong>Il sistema Chiller \u00e8 composto da due parti:<\/strong> l&#039;acqua di raffreddamento entrer\u00e0 in due parti. Uno \u00e8 quello di inserire una posizione della testa di taglio per proteggere il QBH, e un altro \u00e8 quello di proteggere la sorgente laser per raffreddarla e quindi restituirla al refrigeratore d&#039;acqua.<\/li>\n<li><strong>Testa di taglio e seguente sistema:<\/strong> Con sistema di inseguimento automatico della lunghezza focale. La testa della macchina pu\u00f2 mantenere automaticamente la migliore distanza tra la testa di taglio. Il materiale per ottenere la migliore tecnica di taglio.<\/li>\n<li><strong>Sistema di controllo CNC: <\/strong>Il sistema di controllo pu\u00f2 ammettere Windows XP Professional e Windows 7. In modo che possa controllare il taglio della macchina con i parametri richiesti.<\/li>\n<\/ul>","protected":false},"excerpt":{"rendered":"<p>La macchina da taglio laser di tipo aperto HS-1530 1000W \u00e8 disponibile per tutti i tagli di metalli, in particolare per acciaio inossidabile, ferro, alluminio, rame,<\/p>","protected":false},"featured_media":15017,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[18],"product_tag":[423,437,424],"class_list":["post-1511","product","type-product","status-publish","has-post-thumbnail","product_cat-open-type-laser-cutter","product_tag-1000w","product_tag-laser-cutting-machine","product_tag-open-type-laser-cutting-machine","first","instock","shipping-taxable","purchasable","product-type-simple"],"_links":{"self":[{"href":"https:\/\/mydery.com\/it\/wp-json\/wp\/v2\/product\/1511","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mydery.com\/it\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/mydery.com\/it\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/mydery.com\/it\/wp-json\/wp\/v2\/comments?post=1511"}],"version-history":[{"count":0,"href":"https:\/\/mydery.com\/it\/wp-json\/wp\/v2\/product\/1511\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mydery.com\/it\/wp-json\/wp\/v2\/media\/15017"}],"wp:attachment":[{"href":"https:\/\/mydery.com\/it\/wp-json\/wp\/v2\/media?parent=1511"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/mydery.com\/it\/wp-json\/wp\/v2\/product_brand?post=1511"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/mydery.com\/it\/wp-json\/wp\/v2\/product_cat?post=1511"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/mydery.com\/it\/wp-json\/wp\/v2\/product_tag?post=1511"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}